{"id":4412,"date":"2026-02-18T20:28:16","date_gmt":"2026-02-18T20:28:16","guid":{"rendered":"https:\/\/kreazdesserts.com\/product\/coconut-ravani\/"},"modified":"2026-02-18T20:28:16","modified_gmt":"2026-02-18T20:28:16","slug":"coconut-ravani","status":"publish","type":"product","link":"https:\/\/kreazdesserts.com\/en\/product\/coconut-ravani\/","title":{"rendered":"Coconut Ravani"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[87,100],"product_tag":[],"class_list":{"0":"post-4412","1":"product","2":"type-product","3":"status-publish","5":"product_cat-oriental-sweets","6":"product_cat-100","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product\/4412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/comments?post=4412"}],"version-history":[{"count":0,"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product\/4412\/revisions"}],"wp:attachment":[{"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/media?parent=4412"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product_brand?post=4412"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product_cat?post=4412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kreazdesserts.com\/en\/wp-json\/wp\/v2\/product_tag?post=4412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}